{"id":46498,"date":"2026-06-16T16:37:03","date_gmt":"2026-06-16T14:37:03","guid":{"rendered":"https:\/\/galeriemontorgueil.com\/produit\/look-goofy\/"},"modified":"2026-07-08T17:35:12","modified_gmt":"2026-07-08T15:35:12","slug":"look-goofy","status":"publish","type":"product","link":"https:\/\/galeriemontorgueil.com\/en\/produit\/look-goofy\/","title":{"rendered":"Look Goofy !"},"content":{"rendered":"<p>Avec \u00ab Look Goofy ! \u00bb, Geoffrey Bouillot poursuit sa relecture de l\u2019univers du pop art \u00e0 partir de la c\u00e9l\u00e8bre toile \u00ab Look Mickey \u00bb de Roy Lichtenstein. R\u00e9alis\u00e9e en peinture acrylique, l\u2019\u0153uvre transforme la t\u00eate du personnage en un objet sculptural, construit \u00e0 partir de volumes g\u00e9om\u00e9triques et de facettes, o\u00f9 la figure devient structure et forme autonome. Entre abstraction et figuration, la composition s\u2019inscrit dans une approche contemporaine de l\u2019imagerie pop, o\u00f9 l\u2019ic\u00f4ne se d\u00e9tache de son r\u00e9cit pour devenir langage visuel.<br \/>\nComme l\u2019explique l\u2019artiste : \u00ab Pour cette s\u00e9rie Look ! de six formats, je suis parti des personnages de la c\u00e9l\u00e8bre toile Look Mickey de Roy Lichtenstein. J&#8217;ai choisi de peindre leurs t\u00eates comme des objets, pos\u00e9es \u00e0 la mani\u00e8re de la V\u00e9nus de Brancusi enti\u00e8rement r\u00e9adapt\u00e9 dans mon langage. \u00bb<\/p>","protected":false},"excerpt":{"rendered":"<p>Avec \u00ab Look Goofy ! \u00bb, Geoffrey Bouillot poursuit sa relecture de l\u2019univers du pop art \u00e0 partir de la c\u00e9l\u00e8bre toile \u00ab Look Mickey \u00bb de Roy Lichtenstein. R\u00e9alis\u00e9e en peinture acrylique, l\u2019\u0153uvre transforme la t\u00eate du personnage en un objet sculptural, construit \u00e0 partir de volumes g\u00e9om\u00e9triques et de facettes, o\u00f9 la figure [&hellip;]<\/p>\n","protected":false},"featured_media":46497,"template":"","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[97],"product_tag":[],"pa_artistes":[384],"class_list":["post-46498","product","type-product","status-publish","has-post-thumbnail","product_cat-non-classe","pa_artistes-geoffrey-bouillot","pa_types-peinture","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":{"year":"2026","artwork_not_saled":false,"piece_unique":true,"nom_artiste_produit":"","custom_google_title":"","coup_de_coeur":[],"vente_ebay":false,"url_vente_ebay":""},"_links":{"self":[{"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/product\/46498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/media\/46497"}],"wp:attachment":[{"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/media?parent=46498"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/product_brand?post=46498"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/product_cat?post=46498"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/product_tag?post=46498"},{"taxonomy":"pa_artistes","embeddable":true,"href":"https:\/\/galeriemontorgueil.com\/en\/wp-json\/wp\/v2\/pa_artistes?post=46498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}